{"id":133928,"date":"2025-05-02T23:57:24","date_gmt":"2025-05-02T22:57:24","guid":{"rendered":"https:\/\/fallas.com\/?p=133928"},"modified":"2025-05-03T00:23:35","modified_gmt":"2025-05-02T23:23:35","slug":"valentina-tarraga-quesada-bellesa-del-foc-infantil-dalacant-2025","status":"publish","type":"post","link":"https:\/\/fallas.com\/va\/valentina-tarraga-quesada-bellesa-del-foc-infantil-dalacant-2025\/","title":{"rendered":"Valentina T\u00e1rraga Quesada, Bellesa del Foc Infantil d&#8217;Alacant 2025"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: justify;\">La Pla\u00e7a de Bous d&#8217;Alacant ha acollit l&#8217;elecci\u00f3 de la Bellesa del Foc Infantil d&#8217;Alacant 2025. Una nit m\u00e0gica per a les 84 candidates infantils, que ha portat per lema &#8220;Escola de Foc&#8221;, i que ha comptat amb l&#8217;assist\u00e8ncia de Luc\u00eda Garc\u00eda, Fallera Major Infantil de Val\u00e8ncia.<\/p>\n<p style=\"text-align: justify;\">Una nit, sens dubte, molt especial tamb\u00e9 per a Martina Lloret Rocamora, Bellesa del Foc Infantil 2024, que s&#8217;acomiadava de la seua ciutat al costat de les seues Dames d&#8217;Honor amb un emotiu discurs en el qual ha tingut paraules per a les m\u00e0ximes representants infantils de les festes de la Magdalena de Castell\u00f3 i de les Falles de Val\u00e8ncia. Martina, ha recordat a la FMIV de 2024, Marina Garc\u00eda, i tamb\u00e9 ha dedicat unes afectuoses paraules a Luc\u00eda Garc\u00eda, Fallera Major Infantil de Val\u00e8ncia.<\/p>\n<p style=\"text-align: justify;\">L&#8217;acte, presentat per Hugo Olivares de la foguera Carolines, Manuela Moya de Florida Portazgo i Candela M\u00e1s de Sant Blai-La Torreta, ha arribat al seu moment m\u00e9s esperat quan han comen\u00e7at a sonar els noms de les xiquetes triades com a Dames d&#8217;Honor: Adriana Torres Mart\u00ednez de la foguera Sagrada Fam\u00edlia, Sof\u00eda Garc\u00eda Velasco de la foguera Baver-Els Antigons, Elma Garc\u00eda Javaloyes de la foguera Gran V\u00eda-Garbinet, Noa Torres Garc\u00eda de la foguera Jos\u00e9 \u00c1ngel Guirao, Carla Vicedo Morote de la foguera Pla\u00e7a de Santa Maria i Alba Otero Sereix de la foguera Portuaris-Pla del Bon Rep\u00f3s.<\/p>\n<p style=\"text-align: justify;\">Finalment, hem conegut el nom de la Bellesa del Foc Infantil, Valentina T\u00e1rraga Quesada, de la foguera Rabassa, nova m\u00e0xima representant infantil de les Fogueres de Sant Joan d&#8217;Alacant.<\/p>\n<p>Valentina t\u00e9 10 anys, els mateixos que porta en la festa. El seu pare Adri\u00e1n T\u00e1rraga ha sigut president de la seua foguera i la seua mare, In\u00e9s Quesada, va ser la Bellesa del Foc de 2008.\u00a0La nova Bellesa del Foc Infantil estudia 5\u00e9 de prim\u00e0ria, toca el piano i practica tir amb arc i patinatge.<\/p>\n<p>Curiosament, la foguera Rabassa est\u00e0 agermanada amb la falla Arxiduc Carles-Xiva aix\u00ed que, per primera vegada en la hist\u00f2ria, una falla i una foguera agermanades tenen a dos de les seues xiquetes en el m\u00e9s alt de la festa de Val\u00e8ncia i Alacant.<\/p>\n<p>Des de Junta Central Fallera volem donar la nostra m\u00e9s sincera enhorabona a les noves m\u00e0ximes representants infantils de les Fogueres i, en especial, a la Bellesa del Foc Infantil, Valentina T\u00e1rraga Quesada.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;nectarslider_style&#8221; images=&#8221;134103,134101,134099,134097,134095,134093,134091,134089,134087,134085,134083,134081,134079,134077,134075,134073,134071,134069,134067,134065,134063,134061,134059,134057,134055,134053,134051,134049,134047,134045,134043,134041,134039,134037,134035,134033,134031,134029,134027,134025,134023,134021,134019,134017,134015,134013,134011,134009,134007,134005,134003,134001,133999,133997,133995,133993,133991,133989,133987,133985,133983,133981,133979,133977,133975,133973,133971,133969,133967,133965,133963,133961,133959,133957,133955,133953,133951,133949&#8243; image_loading=&#8221;default&#8221; ns_image_rendering=&#8221;default&#8221; ns_image_aspect_ratio=&#8221;16-9&#8243; bullet_navigation_style=&#8221;see_through&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Fotografies: Fotofilmax (JCF)[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":134064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[],"class_list":["post-133928","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-va"],"_links":{"self":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/133928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/comments?post=133928"}],"version-history":[{"count":0,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/133928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media\/134064"}],"wp:attachment":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media?parent=133928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/categories?post=133928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/tags?post=133928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}