{"id":158681,"date":"2025-10-03T22:07:07","date_gmt":"2025-10-03T21:07:07","guid":{"rendered":"https:\/\/fallas.com\/?p=158681"},"modified":"2025-10-04T12:07:29","modified_gmt":"2025-10-04T11:07:29","slug":"la-falla-almirant-i-fundacio-aladina-segellen-el-seu-agermanament-solidari","status":"publish","type":"post","link":"https:\/\/fallas.com\/va\/la-falla-almirant-i-fundacio-aladina-segellen-el-seu-agermanament-solidari\/","title":{"rendered":"La falla Almirant i Fundaci\u00f3 Aladina segellen el seu agermanament solidari"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: justify;\">La comissi\u00f3 de la falla Almirant Cadarso-Comte d&#8217;Altea ha protagonitzat un emotiu acte de germanor amb la Fundaci\u00f3 Aladina, entitat que dedica els seus esfor\u00e7os a donar suport als xiquets i xiquetes que pateixen c\u00e0ncer i a les seues fam\u00edlies.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">L\u2019encontre ha comptat amb la pres\u00e8ncia de la Fallera Major Infantil de Val\u00e8ncia, Luc\u00eda Garc\u00eda, i de la seua Cort d\u2019Honor, que han acompanyat a la comissi\u00f3 en esta jornada tan significativa. Luc\u00eda Garc\u00eda ha dirigit unes paraules als assistents, destacant el valor de la solidaritat i la import\u00e0ncia d\u2019unir la festa amb iniciatives socials que repercutixen positivament en la societat.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9 ha estat present el president de Junta Central Fallera, Santiago Ballester, que ha volgut donar suport amb la seua assist\u00e8ncia a este acte i posar en valor el paper fonamental de les Falles en l\u2019\u00e0mbit social i solidari.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">L\u2019acte refor\u00e7a el comprom\u00eds de les Falles amb les causes solid\u00e0ries i posa de manifest la seua capacitat per anar m\u00e9s enll\u00e0 de la festa i convertir-se en un aut\u00e8ntic motor de suport i esperan\u00e7a.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;nectarslider_style&#8221; images=&#8221;158651,158649,158647,158645,158643,158641,158639,158637,158635,158633,158631,158629,158627,158625,158623,158621,158619,158617,158615,158613,158611,158609,158607,158605&#8243; image_loading=&#8221;default&#8221; ns_image_rendering=&#8221;default&#8221; ns_image_aspect_ratio=&#8221;16-9&#8243; bullet_navigation_style=&#8221;see_through&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Fotografies: Fotofilmax (JCF)[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":158630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[],"class_list":["post-158681","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-va"],"_links":{"self":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/158681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/comments?post=158681"}],"version-history":[{"count":12,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/158681\/revisions"}],"predecessor-version":[{"id":158803,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/158681\/revisions\/158803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media\/158630"}],"wp:attachment":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media?parent=158681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/categories?post=158681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/tags?post=158681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}