{"id":161710,"date":"2025-10-15T21:37:49","date_gmt":"2025-10-15T20:37:49","guid":{"rendered":"https:\/\/fallas.com\/?p=161710"},"modified":"2025-10-18T10:18:47","modified_gmt":"2025-10-18T09:18:47","slug":"teatre-faller-infantil-actor-mora-constitucio-presenta-el-somni-de-noe","status":"publish","type":"post","link":"https:\/\/fallas.com\/va\/teatre-faller-infantil-actor-mora-constitucio-presenta-el-somni-de-noe\/","title":{"rendered":"TEATRE FALLER INFANTIL &#8211; Actor Mora-Constituci\u00f3 presenta &#8216;El somni de No\u00e9&#8217;"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Comissi\u00f3:<\/strong> Actor Mora-Constituci\u00f3<\/p>\n<p><strong>Categora: <\/strong>Infantil<\/p>\n<p><strong>Data:<\/strong> 12 d&#8217;octubre, 19:00 h<\/p>\n<p><strong>Obra in\u00e8dita<\/strong><strong>:<\/strong>\u00a0 &#8216;EL SOMNI DE NO\u00c9&#8217;<\/p>\n<p><strong>Autor:<\/strong> Francisco Sarro Oltra<\/p>\n<p><strong>Director<\/strong>: Rub\u00e9n G\u00f3mez Garc\u00eda<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REPARTIMENT<\/strong><\/p>\n<p>NO\u00c9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 Pablo Contelles Cervera (*)<\/p>\n<p>MARI\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 L\u00eda G\u00f3mez Navarro (*)<\/p>\n<p>DEU\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Anna Llorens Garc\u00eda (*)<\/p>\n<p>CONSCIENCIA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Isabel Costa De Gea (*)<\/p>\n<p>VE\u00cd\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 V\u00edctor Ribes Mart\u00ed (*)<\/p>\n<p>VEINA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sof\u00eda Rutiz Marco (*)<\/p>\n<p>FILL 1\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Aitana Almecija Berga (*) (**)<\/p>\n<p>FILL 2\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cesc Gabarda Pe\u00f1arrocha (*) (**)<\/p>\n<p>FILL 3\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Fco. Contelles Cervera (*) (**)<\/p>\n<p>ANIMALET GRANJA 1\u00a0\u00a0\u00a0\u00a0\u00a0 Bernat Manuel Hidalgo Mart\u00ednez (*) (**)<\/p>\n<p>ANIMALET GRANJA 2\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Marcos Ribes Mart\u00ed (*) (**)<\/p>\n<p>ANIMALET GRANJA 3\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Allegra S\u00e1ez Mart\u00ednez, (*) (**)<\/p>\n<p>ANIMALET GRANJA 4\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Valentina S\u00e1ez Mart\u00ednez (*) (**)<\/p>\n<p>ANIMALET GRANJA 5\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Carmen Blat Torres (*) (**)<\/p>\n<p>ANIMALET GRANJA 6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Jos\u00e9 Blat Torres (*) (**)<\/p>\n<p>ANIMALET GRANJA 7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bernabeu Del Olmo, Allegra (*) (**)<\/p>\n<p>ANIMALET GRANJA 8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Valent\u00edn Legora (*) (**)<\/p>\n<p>ANIMALET GRANJA 9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bautista Rutiz Marco (*) (**)<\/p>\n<p>ANIMALET GRANJA 10\u00a0\u00a0\u00a0\u00a0 Marcos Quesada Barbena (*) (**)<\/p>\n<p>(*) Actor\/actriu novell (**) Actor\/actriu menut\/menuda<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SINOPSI<\/strong><\/p>\n<p>En una granja de la comarca del Camp del T\u00faria vivia un humil granger. Preocupat per la sequera que afectava l\u00b4horta i els seus animalets, per\u00f2 sobretot, pels ve\u00efns burletes i envejosos, no feia m\u00e9s que encabotarse en la pluja que anava a caure i de la que se anaven a cagar tots\u2026 En uns dels tants somnis que tenia, se li va apar\u00e9ixer Deu i es va creure que era No\u00e9\u2026<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Duraci\u00f3:<\/strong> 36m<\/p>\n<p><strong>Assistents:<\/strong> 100[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":161677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[651,309],"tags":[],"class_list":["post-161710","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-va","category-noticias-va"],"_links":{"self":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/161710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/comments?post=161710"}],"version-history":[{"count":17,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/161710\/revisions"}],"predecessor-version":[{"id":162057,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/161710\/revisions\/162057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media\/161677"}],"wp:attachment":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media?parent=161710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/categories?post=161710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/tags?post=161710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}