{"id":164447,"date":"2025-10-27T23:59:12","date_gmt":"2025-10-27T22:59:12","guid":{"rendered":"https:\/\/fallas.com\/?p=164447"},"modified":"2025-10-28T21:11:42","modified_gmt":"2025-10-28T20:11:42","slug":"presa-de-mides-de-les-sabates-oficials-en-creaciones-aurora","status":"publish","type":"post","link":"https:\/\/fallas.com\/va\/presa-de-mides-de-les-sabates-oficials-en-creaciones-aurora\/","title":{"rendered":"Presa de mides de les sabates oficials en Creaciones Aurora"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: justify;\">Les Falleres Majors de Val\u00e8ncia, Carmen Prades i Marta Mercader, acompanyades de les seues Corts d&#8217;Honor, acudixen estos dies als tallers i establiments dels indumentaristes oficials per a la presa de mides de cara a la creaci\u00f3 de les diferents peces i complements que lluiran durant tot l&#8217;any.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">Esta vesprada han visitat Creacions Aurora, l&#8217;empresa encarregada del disseny i la realitzaci\u00f3 de les sabates tant del seu primer vestit com del segon.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">Carmen i Marta, i les 24 components de les Corts d&#8217;Honor, molt il\u00b7lusionades d&#8217;anar coneixent cada detall de la indument\u00e0ria que del seu regnat, comptaran amb la comoditat de les sabates d&#8217;esta empresa valenciana que per segon any consecutiu s&#8217;encarrega de la realitzaci\u00f3 de les sabates de les nostres m\u00e0ximes representants.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;nectarslider_style&#8221; images=&#8221;164605,164603,164601,164599,164597,164595,164593,164591,164589,164587,164585,164583,164581,164579,164577,164575,164573,164571,164569,164567,164565,164563,164561,164559,164557,164555,164553,164551,164549,164547,164545,164543,164541,164539,164537,164535,164533,164531,164529,164527,164525,164523,164521,164519,164517,164515,164513,164511,164509,164507,164505,164503,164501,164499,164497,164495,164493,164491,164489,164487,164485,164483,164481,164479,164477,164475,164473,164471,164469,164467,164465,164463,164461,164459,164457,164455,164453,164451&#8243; image_loading=&#8221;default&#8221; ns_image_rendering=&#8221;default&#8221; ns_image_aspect_ratio=&#8221;16-9&#8243; bullet_navigation_style=&#8221;see_through&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Fotografies: Fotofilmax (JCF)[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":164522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[],"class_list":["post-164447","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-va"],"_links":{"self":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/164447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/comments?post=164447"}],"version-history":[{"count":7,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/164447\/revisions"}],"predecessor-version":[{"id":164612,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/164447\/revisions\/164612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media\/164522"}],"wp:attachment":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media?parent=164447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/categories?post=164447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/tags?post=164447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}