{"id":164910,"date":"2025-11-03T19:16:00","date_gmt":"2025-11-03T18:16:00","guid":{"rendered":"https:\/\/fallas.com\/?p=164910"},"modified":"2025-11-03T20:33:51","modified_gmt":"2025-11-03T19:33:51","slug":"segona-jornada-de-la-xxviii-edicio-de-balls-al-carrer","status":"publish","type":"post","link":"https:\/\/fallas.com\/va\/segona-jornada-de-la-xxviii-edicio-de-balls-al-carrer\/","title":{"rendered":"Segona jornada de la XXVIII edici\u00f3 de Balls al Carrer"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: justify;\">Este cap de setmana s&#8217;ha celebrat la segona jornada de la XXVIII edici\u00f3 del Festival de Balls al Carrer que cada any organitza la delegaci\u00f3 de Cultura de Junta Central Fallera.<\/p>\n<p><strong>Empla\u00e7ament:<\/strong> Pla\u00e7a de la Reina<\/p>\n<p><strong>Data<\/strong>: 2 de novembre<\/p>\n<p><strong>Comissiones participants:<\/strong><\/p>\n<ol>\n<li>Ferran el Cat\u00f2lic-\u00c1ngel Guimer\u00e1<\/li>\n<li>Antiga Senda Senent-Passeig de l&#8217;Albereda<\/li>\n<li>Joaqu\u00edn Costa-Borriana<\/li>\n<li>Illes Can\u00e0ria-Dama d&#8217;Elx<\/li>\n<li>Lo Rat Penat<\/li>\n<li>Avinguda Regne de Val\u00e8ncia-Sant Valero<\/li>\n<li>Progr\u00e9s-Teatre de la Marina<\/li>\n<li>Polo i Peyrol\u00f3n-Ciutat de Mula<\/li>\n<\/ol>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;nectarslider_style&#8221; images=&#8221;164906,164904,164902,164900,164898,164896,164894,164891,164889,164887,164885,164883,164881,164879,164876,164874,164872,164870,164868,164866,164864,164862,164860,164858,164856,164854,164852,164850,164848,164846,164844,164842,164840&#8243; image_loading=&#8221;default&#8221; ns_image_rendering=&#8221;default&#8221; ns_image_aspect_ratio=&#8221;16-9&#8243; bullet_navigation_style=&#8221;see_through&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Fotograf\u00edas: JCF[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":164861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[651,309],"tags":[],"class_list":["post-164910","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-va","category-noticias-va"],"_links":{"self":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/164910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/comments?post=164910"}],"version-history":[{"count":6,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/164910\/revisions"}],"predecessor-version":[{"id":165008,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/164910\/revisions\/165008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media\/164861"}],"wp:attachment":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media?parent=164910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/categories?post=164910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/tags?post=164910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}