{"id":170143,"date":"2025-11-20T21:43:13","date_gmt":"2025-11-20T20:43:13","guid":{"rendered":"https:\/\/fallas.com\/?p=170143"},"modified":"2025-11-21T12:48:44","modified_gmt":"2025-11-21T11:48:44","slug":"nuevo-centro-dona-la-benvinguda-al-nadal","status":"publish","type":"post","link":"https:\/\/fallas.com\/va\/nuevo-centro-dona-la-benvinguda-al-nadal\/","title":{"rendered":"Nuevo Centro dona la benvinguda al Nadal"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: justify;\">El centre comercial Nuevo Centro ha donat la benvinguda a una de les \u00e8poques m\u00e9s m\u00e0giques i entranyables de l&#8217;any amb el seu tradicional enc\u00e9s de llums de Nadal.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">Les Falleres Majors de Val\u00e8ncia, Carmen Prades i Marta Mercader, acompanyades per les seues Corts d&#8217;Honor, han sigut, un any m\u00e9s, les encarregades d&#8217;encendre Nadal en el centre comercial. Previ a l&#8217;encesa, tot el p\u00fablic assistent ha pogut disfrutar d&#8217;una emotiva actuaci\u00f3 a c\u00e0rrec del Cor del Col\u00b7legi El Vedat de Torrent que ha omplit d&#8217;esperit nadalenc l&#8217;emblem\u00e0tica pla\u00e7a exterior de Nuevo Centro.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3, han visitat el Betlem monumental creat per l&#8217;Associaci\u00f3 de Belenistas de Val\u00e8ncia que compta amb 27 metres quadrats d&#8217;escenes artesanals i ens transporta a la Palestina de fa m\u00e9s de 2.000 anys amb un recorregut ple de vida i xicotets detalls.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">El Betlem, instal\u00b7lat a la Casa del Nadal situada en la pla\u00e7a, podr\u00e0 visitar-se fins al 5 de gener de 2026.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery css=&#8221;&#8221; type=&#8221;nectarslider_style&#8221; images=&#8221;170139,170137,170135,170133,170131,170129,170127,170125,170123,170121,170119,170117,170115,170113,170111,170109,170107,170105,170103,170101,170099,170097,170095,170093,170091,170089,170087,170085,170083,170081,170079,170077,170075,170073,170071,170069,170067,170064,170062,170060,170058,170056,170054&#8243; image_loading=&#8221;default&#8221; ns_image_rendering=&#8221;default&#8221; ns_image_aspect_ratio=&#8221;16-9&#8243; bullet_navigation_style=&#8221;see_through&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Fotografies: Fotofilmax (JCF)[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":170080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[],"class_list":["post-170143","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-va"],"_links":{"self":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/170143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/comments?post=170143"}],"version-history":[{"count":12,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/170143\/revisions"}],"predecessor-version":[{"id":170373,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/posts\/170143\/revisions\/170373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media\/170080"}],"wp:attachment":[{"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/media?parent=170143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/categories?post=170143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fallas.com\/va\/wp-json\/wp\/v2\/tags?post=170143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}